{"id":25990,"date":"2025-05-29T12:00:00","date_gmt":"2025-05-29T17:00:00","guid":{"rendered":"https:\/\/icazalaw.com\/?p=25990"},"modified":"2025-06-05T16:51:59","modified_gmt":"2025-06-05T21:51:59","slug":"icaza-recibe-reconocimiento-de-la-usma","status":"publish","type":"post","link":"https:\/\/icazalaw.com\/es\/2025\/05\/icaza-recibe-reconocimiento-de-la-usma\/","title":{"rendered":"Icaza recibe reconocimiento de la USMA"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Nuestro socio <a href=\"https:\/\/icazalaw.com\/es\/expertos\/javier-vallarino\/\"><strong>Javier Vallarino<\/strong> <\/a>en representaci\u00f3n de Icaza recibi\u00f3 reconocimiento de la Universidad Santa Mar\u00eda la Antigua (USMA) por la constante participaci\u00f3n y patrocinios a AEDUSMA<\/h3>\n\n\n\n<p>Icaza fue reconocido por la Asociaci\u00f3n de Estudiantes de Derecho y Ciencias Pol\u00edticas de la Universidad Santa Mar\u00eda la Antigua (AEDUSMA) por su valioso patrocinio y constante apoyo en la realizaci\u00f3n de actividades acad\u00e9micas organizadas por la asociaci\u00f3n. <\/p>\n\n\n\n<p>Durante el evento, tambi\u00e9n se otorg\u00f3 un reconocimiento especial a nuestro socio <strong><a href=\"https:\/\/icazalaw.com\/es\/expertos\/javier-vallarino\/\">Javier Vallarino<\/a><\/strong>, quien particip\u00f3 como expositor en dos de las actividades organizadas por AEDUSMA, compartiendo su experiencia y conocimientos con la comunidad estudiantil y profesional. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"25997\" src=\"https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/1-6-1024x683.jpg\" alt=\"\" class=\"wp-image-25997\" srcset=\"https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/1-6-1024x683.jpg 1024w, https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/1-6-300x200.jpg 300w, https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/1-6-150x100.jpg 150w, https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/1-6-768x512.jpg 768w, https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/1-6-1536x1024.jpg 1536w, https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/1-6-2048x1365.jpg 2048w, https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/1-6-113x75.jpg 113w, https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/1-6-480x320.jpg 480w\" sizes=\"(max-width:767px) 480px, (max-width:1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"25995\" src=\"https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/2-4-1024x683.jpg\" alt=\"\" class=\"wp-image-25995\" srcset=\"https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/2-4-1024x683.jpg 1024w, https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/2-4-300x200.jpg 300w, https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/2-4-150x100.jpg 150w, https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/2-4-768x512.jpg 768w, https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/2-4-1536x1024.jpg 1536w, https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/2-4-2048x1365.jpg 2048w, https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/2-4-113x75.jpg 113w, https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/2-4-480x320.jpg 480w\" sizes=\"(max-width:767px) 480px, (max-width:1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Nuestro socio Javier Vallarino en representaci\u00f3n de Icaza recibi\u00f3 reconocimiento de la Universidad Santa Mar\u00eda la Antigua (USMA)<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":17,"featured_media":25997,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[1173],"tags":[1214,943,808,787,1228],"class_list":["post-25990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-2","tag-1214","tag-icaza-gonzalez-ruiz-aleman-es-2","tag-javier-vallarino-es-2","tag-laboral-es","tag-usma"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Icaza recibe reconocimiento de la USMA - Icaza, Gonz\u00e1lez-Ruiz &amp; Alem\u00e1n<\/title>\n<meta name=\"description\" content=\"Icaza fue reconocido por AEDUSMA por su patrocinio y apoyo acad\u00e9mico; Javier Vallarino destac\u00f3 como expositor en eventos jur\u00eddicos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/icazalaw.com\/es\/2025\/05\/icaza-recibe-reconocimiento-de-la-usma\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Icaza recibe reconocimiento de la USMA\" \/>\n<meta property=\"og:description\" content=\"Icaza fue reconocido por AEDUSMA por su patrocinio y apoyo acad\u00e9mico; Javier Vallarino destac\u00f3 como expositor en eventos jur\u00eddicos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/icazalaw.com\/es\/2025\/05\/icaza-recibe-reconocimiento-de-la-usma\/\" \/>\n<meta property=\"og:site_name\" content=\"Icaza, Gonz\u00e1lez-Ruiz &amp; Alem\u00e1n\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-29T17:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-05T21:51:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/1-6-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrea Camargo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Camargo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/2025\\\/05\\\/icaza-recibe-reconocimiento-de-la-usma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/2025\\\/05\\\/icaza-recibe-reconocimiento-de-la-usma\\\/\"},\"author\":{\"name\":\"Andrea Camargo\",\"@id\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/#\\\/schema\\\/person\\\/b35fe9845de3a66c12ae4ca2f957c4b9\"},\"headline\":\"Icaza recibe reconocimiento de la USMA\",\"datePublished\":\"2025-05-29T17:00:00+00:00\",\"dateModified\":\"2025-06-05T21:51:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/2025\\\/05\\\/icaza-recibe-reconocimiento-de-la-usma\\\/\"},\"wordCount\":117,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/2025\\\/05\\\/icaza-recibe-reconocimiento-de-la-usma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/icazalaw.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/1-6-scaled.jpg\",\"keywords\":[\"2025\",\"Icaza Gonz\u00e1lez-Ruiz &amp; Alem\u00e1n\",\"Javier Vallarino\",\"laboral\",\"USMA\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/icazalaw.com\\\/es\\\/2025\\\/05\\\/icaza-recibe-reconocimiento-de-la-usma\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/2025\\\/05\\\/icaza-recibe-reconocimiento-de-la-usma\\\/\",\"url\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/2025\\\/05\\\/icaza-recibe-reconocimiento-de-la-usma\\\/\",\"name\":\"Icaza recibe reconocimiento de la USMA - Icaza, Gonz\u00e1lez-Ruiz &amp; Alem\u00e1n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/2025\\\/05\\\/icaza-recibe-reconocimiento-de-la-usma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/2025\\\/05\\\/icaza-recibe-reconocimiento-de-la-usma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/icazalaw.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/1-6-scaled.jpg\",\"datePublished\":\"2025-05-29T17:00:00+00:00\",\"dateModified\":\"2025-06-05T21:51:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/#\\\/schema\\\/person\\\/b35fe9845de3a66c12ae4ca2f957c4b9\"},\"description\":\"Icaza fue reconocido por AEDUSMA por su patrocinio y apoyo acad\u00e9mico; Javier Vallarino destac\u00f3 como expositor en eventos jur\u00eddicos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/2025\\\/05\\\/icaza-recibe-reconocimiento-de-la-usma\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/icazalaw.com\\\/es\\\/2025\\\/05\\\/icaza-recibe-reconocimiento-de-la-usma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/2025\\\/05\\\/icaza-recibe-reconocimiento-de-la-usma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/icazalaw.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/1-6-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/icazalaw.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/1-6-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/2025\\\/05\\\/icaza-recibe-reconocimiento-de-la-usma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Icaza recibe reconocimiento de la USMA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/\",\"name\":\"Icaza, Gonz\u00e1lez-Ruiz &amp; Alem\u00e1n\",\"description\":\"Full-service law firm providing practical legal solutions to corporate and private clients worldwide.\",\"alternateName\":\"IGRA Attorneys\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/#\\\/schema\\\/person\\\/b35fe9845de3a66c12ae4ca2f957c4b9\",\"name\":\"Andrea Camargo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9cd144181868c74eac53a2b680913a1f4c3a308071f2bf86ac1ce17c6d9c0b57?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9cd144181868c74eac53a2b680913a1f4c3a308071f2bf86ac1ce17c6d9c0b57?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9cd144181868c74eac53a2b680913a1f4c3a308071f2bf86ac1ce17c6d9c0b57?s=96&d=mm&r=g\",\"caption\":\"Andrea Camargo\"},\"url\":\"https:\\\/\\\/icazalaw.com\\\/es\\\/author\\\/stinoco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Icaza recibe reconocimiento de la USMA - Icaza, Gonz\u00e1lez-Ruiz &amp; Alem\u00e1n","description":"Icaza fue reconocido por AEDUSMA por su patrocinio y apoyo acad\u00e9mico; Javier Vallarino destac\u00f3 como expositor en eventos jur\u00eddicos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/icazalaw.com\/es\/2025\/05\/icaza-recibe-reconocimiento-de-la-usma\/","og_locale":"es_ES","og_type":"article","og_title":"Icaza recibe reconocimiento de la USMA","og_description":"Icaza fue reconocido por AEDUSMA por su patrocinio y apoyo acad\u00e9mico; Javier Vallarino destac\u00f3 como expositor en eventos jur\u00eddicos.","og_url":"https:\/\/icazalaw.com\/es\/2025\/05\/icaza-recibe-reconocimiento-de-la-usma\/","og_site_name":"Icaza, Gonz\u00e1lez-Ruiz &amp; Alem\u00e1n","article_published_time":"2025-05-29T17:00:00+00:00","article_modified_time":"2025-06-05T21:51:59+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/1-6-scaled.jpg","type":"image\/jpeg"}],"author":"Andrea Camargo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andrea Camargo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/icazalaw.com\/es\/2025\/05\/icaza-recibe-reconocimiento-de-la-usma\/#article","isPartOf":{"@id":"https:\/\/icazalaw.com\/es\/2025\/05\/icaza-recibe-reconocimiento-de-la-usma\/"},"author":{"name":"Andrea Camargo","@id":"https:\/\/icazalaw.com\/es\/#\/schema\/person\/b35fe9845de3a66c12ae4ca2f957c4b9"},"headline":"Icaza recibe reconocimiento de la USMA","datePublished":"2025-05-29T17:00:00+00:00","dateModified":"2025-06-05T21:51:59+00:00","mainEntityOfPage":{"@id":"https:\/\/icazalaw.com\/es\/2025\/05\/icaza-recibe-reconocimiento-de-la-usma\/"},"wordCount":117,"commentCount":0,"image":{"@id":"https:\/\/icazalaw.com\/es\/2025\/05\/icaza-recibe-reconocimiento-de-la-usma\/#primaryimage"},"thumbnailUrl":"https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/1-6-scaled.jpg","keywords":["2025","Icaza Gonz\u00e1lez-Ruiz &amp; Alem\u00e1n","Javier Vallarino","laboral","USMA"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/icazalaw.com\/es\/2025\/05\/icaza-recibe-reconocimiento-de-la-usma\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/icazalaw.com\/es\/2025\/05\/icaza-recibe-reconocimiento-de-la-usma\/","url":"https:\/\/icazalaw.com\/es\/2025\/05\/icaza-recibe-reconocimiento-de-la-usma\/","name":"Icaza recibe reconocimiento de la USMA - Icaza, Gonz\u00e1lez-Ruiz &amp; Alem\u00e1n","isPartOf":{"@id":"https:\/\/icazalaw.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/icazalaw.com\/es\/2025\/05\/icaza-recibe-reconocimiento-de-la-usma\/#primaryimage"},"image":{"@id":"https:\/\/icazalaw.com\/es\/2025\/05\/icaza-recibe-reconocimiento-de-la-usma\/#primaryimage"},"thumbnailUrl":"https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/1-6-scaled.jpg","datePublished":"2025-05-29T17:00:00+00:00","dateModified":"2025-06-05T21:51:59+00:00","author":{"@id":"https:\/\/icazalaw.com\/es\/#\/schema\/person\/b35fe9845de3a66c12ae4ca2f957c4b9"},"description":"Icaza fue reconocido por AEDUSMA por su patrocinio y apoyo acad\u00e9mico; Javier Vallarino destac\u00f3 como expositor en eventos jur\u00eddicos.","breadcrumb":{"@id":"https:\/\/icazalaw.com\/es\/2025\/05\/icaza-recibe-reconocimiento-de-la-usma\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/icazalaw.com\/es\/2025\/05\/icaza-recibe-reconocimiento-de-la-usma\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/icazalaw.com\/es\/2025\/05\/icaza-recibe-reconocimiento-de-la-usma\/#primaryimage","url":"https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/1-6-scaled.jpg","contentUrl":"https:\/\/icazalaw.com\/wp-content\/uploads\/2025\/06\/1-6-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/icazalaw.com\/es\/2025\/05\/icaza-recibe-reconocimiento-de-la-usma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/icazalaw.com\/es\/"},{"@type":"ListItem","position":2,"name":"Icaza recibe reconocimiento de la USMA"}]},{"@type":"WebSite","@id":"https:\/\/icazalaw.com\/es\/#website","url":"https:\/\/icazalaw.com\/es\/","name":"Icaza, Gonz\u00e1lez-Ruiz &amp; Alem\u00e1n","description":"Full-service law firm providing practical legal solutions to corporate and private clients worldwide.","alternateName":"IGRA Attorneys","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/icazalaw.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/icazalaw.com\/es\/#\/schema\/person\/b35fe9845de3a66c12ae4ca2f957c4b9","name":"Andrea Camargo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9cd144181868c74eac53a2b680913a1f4c3a308071f2bf86ac1ce17c6d9c0b57?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9cd144181868c74eac53a2b680913a1f4c3a308071f2bf86ac1ce17c6d9c0b57?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9cd144181868c74eac53a2b680913a1f4c3a308071f2bf86ac1ce17c6d9c0b57?s=96&d=mm&r=g","caption":"Andrea Camargo"},"url":"https:\/\/icazalaw.com\/es\/author\/stinoco\/"}]}},"_links":{"self":[{"href":"https:\/\/icazalaw.com\/es\/wp-json\/wp\/v2\/posts\/25990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/icazalaw.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/icazalaw.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/icazalaw.com\/es\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/icazalaw.com\/es\/wp-json\/wp\/v2\/comments?post=25990"}],"version-history":[{"count":2,"href":"https:\/\/icazalaw.com\/es\/wp-json\/wp\/v2\/posts\/25990\/revisions"}],"predecessor-version":[{"id":26003,"href":"https:\/\/icazalaw.com\/es\/wp-json\/wp\/v2\/posts\/25990\/revisions\/26003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/icazalaw.com\/es\/wp-json\/wp\/v2\/media\/25997"}],"wp:attachment":[{"href":"https:\/\/icazalaw.com\/es\/wp-json\/wp\/v2\/media?parent=25990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/icazalaw.com\/es\/wp-json\/wp\/v2\/categories?post=25990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/icazalaw.com\/es\/wp-json\/wp\/v2\/tags?post=25990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}